{"id":25405,"date":"2026-04-02T15:35:55","date_gmt":"2026-04-02T15:35:55","guid":{"rendered":"https:\/\/protect-lawyers.org\/case\/chinette-gallichan\/"},"modified":"2026-04-06T10:28:41","modified_gmt":"2026-04-06T10:28:41","slug":"chinette-gallichan","status":"publish","type":"listing","link":"https:\/\/protect-lawyers.org\/es\/case\/chinette-gallichan\/","title":{"rendered":"Chinette Gallichan"},"content":{"rendered":"<h2>Sud\u00e1frica: Asesinato de la abogada Chinette Gallichan en Johannesburgo<\/h2>\n<p><strong>1 de abril de 2026<\/strong><\/p>\n<p>\u00a0<\/p>\n<p><strong>El OIAD expresa su profunda preocupaci\u00f3n tras la muerte violenta de la abogada sudafricana Chinette Gallichan, de 35 a\u00f1os, asesinada a tiros en Johannesburgo el lunes 23 de marzo.<\/strong><\/p>\n<p>La Sra. Gallichan ejerc\u00eda principalmente en el \u00e1mbito del derecho laboral e interven\u00eda en litigios entre empleadores y trabajadores. En particular, estaba implicada en casos relacionados con procesos de impugnaci\u00f3n de despidos y reclamaciones de indemnizaci\u00f3n en el sector minero<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>La abogada se encontraba cerca de las oficinas de la <em>Commission for Conciliation, Mediation and Arbitration<\/em> (CCMA), donde deb\u00eda intervenir en un asunto de derecho laboral. Un individuo se le habr\u00eda acercado y le habr\u00eda disparado a quemarropa antes de huir del lugar.<\/p>\n<p>Ninguno de sus objetos personales fue sustra\u00eddo; varias fuentes apuntan a la posibilidad de un ataque dirigido. Se ha abierto una investigaci\u00f3n para determinar las circunstancias exactas de este asesinato.<\/p>\n<p>El asesinato de la Sra. Gallichan ha suscitado una gran conmoci\u00f3n entre sus compa\u00f1eros y compa\u00f1eras, quienes destacan su compromiso profesional en la defensa del derecho laboral en Sud\u00e1frica.<\/p>\n<p><strong>El Observatorio expresa sus <\/strong>condolencias a los familiares, compa\u00f1eros\/as y al conjunto de la abogac\u00eda sudafricana.<\/p>\n<p><strong>El Observatorio insta a las autoridades sudafricanas<\/strong> a llevar a cabo una investigaci\u00f3n exhaustiva, independiente e imparcial con el fin de identificar a los responsables de este asesinato y esclarecer plenamente este crimen.<\/p>\n<p><strong>El Observatorio subraya<\/strong> que cualquier atentado contra la integridad f\u00edsica de un abogado\/a debido a sus funciones constituye una amenaza directa para el acceso a la justicia y la independencia del sistema judicial, tal como se consagran en la Constituci\u00f3n sudafricana.<\/p>\n<p><strong>El Observatorio a\u00f1ade <\/strong>que, de conformidad con los <a href=\"https:\/\/www.ohchr.org\/fr\/instruments-mechanisms\/instruments\/basic-principles-role-lawyers\" target=\"_blank\" rel=\"noopener\">Principios de La Habana<\/a>, los abogados deben poder ejercer su labor sin temor a represalias, incluso en contextos de litigios particularmente sensibles.<\/p>\n<p><strong>El Observatorio recuerda<\/strong> que, conforme a dichos <a href=\"https:\/\/www.ohchr.org\/fr\/instruments-mechanisms\/instruments\/basic-principles-role-lawyers\" target=\"_blank\" rel=\"noopener\">principios relativos<\/a> a la funci\u00f3n de la abogac\u00eda, los Estados tienen la obligaci\u00f3n de garantizar la protecci\u00f3n de la abogac\u00eda en el ejercicio de sus funciones.<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> El sector minero en Sud\u00e1frica est\u00e1 regularmente marcado por conflictos sociales y litigios sensibles, como lo demostr\u00f3 el ejemplo de la <a href=\"https:\/\/www.ifri.org\/fr\/editoriaux\/que-nous-revele-le-drame-de-marikana-sur-letat-de-la-societe-sud-africaine\" target=\"_blank\" rel=\"noopener\">masacre de Marikana en 2012<\/a>.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[64],"event_category":[],"service_category":[],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[74,2030],"class_list":["post-25405","listing","type-listing","status-publish","hentry","listing_category-fallecidos","region-africa","region-sudafrica"],"_links":{"self":[{"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing\/25405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/comments?post=25405"}],"version-history":[{"count":6,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing\/25405\/revisions"}],"predecessor-version":[{"id":25442,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing\/25405\/revisions\/25442"}],"wp:attachment":[{"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/media?parent=25405"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing_category?post=25405"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/event_category?post=25405"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/service_category?post=25405"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/rental_category?post=25405"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/classifieds_category?post=25405"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/listing_feature?post=25405"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/protect-lawyers.org\/es\/wp-json\/wp\/v2\/region?post=25405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}